{"id":44183,"date":"2025-07-14T21:40:27","date_gmt":"2025-07-14T19:40:27","guid":{"rendered":"https:\/\/tossacycling.com\/?post_type=product&#038;p=44183"},"modified":"2025-07-14T21:52:08","modified_gmt":"2025-07-14T19:52:08","slug":"gravel_odyssey_girona_rental_bicycle","status":"publish","type":"product","link":"https:\/\/tossacycling.com\/en\/shop\/salidas_guiadas\/gravel_odyssey_girona_rental_bicycle\/","title":{"rendered":"Gravel Odyssey Girona + Rental Bike"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":44113,"template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[291],"product_tag":[],"class_list":{"0":"post-44183","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-salidas_guiadas","8":"first","9":"instock","10":"virtual","11":"sold-individually","12":"taxable","13":"purchasable","14":"product-type-booking"},"booking_location":"","booking_location_type":"","booking_duration":1,"booking_duration_unit":"day","booking_buffer":0,"booking_cost":0,"booking_resources":[13535,21940,21941,21951,23285,27483,28661,28662,28663,32255,35059,35060,21939,16948,13537,13538,13539,13540,13541,13542,13548,15650,15651,16946,16947,35062],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gravel Odyssey Girona + Rental Bike | TOSSA CYCLING<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tossacycling.com\/en\/shop\/salidas_guiadas\/gravel_odyssey_girona_rental_bicycle\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gravel Odyssey Girona + Rental Bike | TOSSA CYCLING\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tossacycling.com\/en\/shop\/salidas_guiadas\/gravel_odyssey_girona_rental_bicycle\/\" \/>\n<meta property=\"og:site_name\" content=\"TOSSA CYCLING\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TossaCycling\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T19:52:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tossacycling.com\/wp-content\/uploads\/2025\/07\/GOG.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/shop\\\/salidas_guiadas\\\/gravel_odyssey_girona_rental_bicycle\\\/\",\"url\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/shop\\\/salidas_guiadas\\\/gravel_odyssey_girona_rental_bicycle\\\/\",\"name\":\"Gravel Odyssey Girona + Rental Bike | TOSSA CYCLING\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/shop\\\/salidas_guiadas\\\/gravel_odyssey_girona_rental_bicycle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tossacycling.com\\\/shop\\\/salidas_guiadas\\\/gravel_odyssey_girona_rental_bicycle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tossacycling.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/GOG.png\",\"datePublished\":\"2025-07-14T19:40:27+00:00\",\"dateModified\":\"2025-07-14T19:52:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/shop\\\/salidas_guiadas\\\/gravel_odyssey_girona_rental_bicycle\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/tossacycling.com\\\/en\\\/shop\\\/salidas_guiadas\\\/gravel_odyssey_girona_rental_bicycle\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/shop\\\/salidas_guiadas\\\/gravel_odyssey_girona_rental_bicycle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tossacycling.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/GOG.png\",\"contentUrl\":\"https:\\\/\\\/tossacycling.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/GOG.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/shop\\\/salidas_guiadas\\\/gravel_odyssey_girona_rental_bicycle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gravel Odyssey Girona + Rental Bike\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/\",\"name\":\"TOSSA CYCLING\",\"description\":\"CYCLING &amp; GOOD VIBES\",\"publisher\":{\"@id\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/#organization\",\"name\":\"TOSSA CYCLING\",\"url\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tossacycling.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-squareRecurso-2.png\",\"contentUrl\":\"https:\\\/\\\/tossacycling.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-squareRecurso-2.png\",\"width\":512,\"height\":512,\"caption\":\"TOSSA CYCLING\"},\"image\":{\"@id\":\"https:\\\/\\\/tossacycling.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TossaCycling\",\"https:\\\/\\\/www.instagram.com\\\/tossacycling\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gravel Odyssey Girona + Rental Bike | TOSSA CYCLING","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tossacycling.com\/en\/shop\/salidas_guiadas\/gravel_odyssey_girona_rental_bicycle\/","og_locale":"en_US","og_type":"article","og_title":"Gravel Odyssey Girona + Rental Bike | TOSSA CYCLING","og_url":"https:\/\/tossacycling.com\/en\/shop\/salidas_guiadas\/gravel_odyssey_girona_rental_bicycle\/","og_site_name":"TOSSA CYCLING","article_publisher":"https:\/\/www.facebook.com\/TossaCycling","article_modified_time":"2025-07-14T19:52:08+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/tossacycling.com\/wp-content\/uploads\/2025\/07\/GOG.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/tossacycling.com\/en\/shop\/salidas_guiadas\/gravel_odyssey_girona_rental_bicycle\/","url":"https:\/\/tossacycling.com\/en\/shop\/salidas_guiadas\/gravel_odyssey_girona_rental_bicycle\/","name":"Gravel Odyssey Girona + Rental Bike | TOSSA CYCLING","isPartOf":{"@id":"https:\/\/tossacycling.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tossacycling.com\/en\/shop\/salidas_guiadas\/gravel_odyssey_girona_rental_bicycle\/#primaryimage"},"image":{"@id":"https:\/\/tossacycling.com\/shop\/salidas_guiadas\/gravel_odyssey_girona_rental_bicycle\/#primaryimage"},"thumbnailUrl":"https:\/\/tossacycling.com\/wp-content\/uploads\/2025\/07\/GOG.png","datePublished":"2025-07-14T19:40:27+00:00","dateModified":"2025-07-14T19:52:08+00:00","breadcrumb":{"@id":"https:\/\/tossacycling.com\/en\/shop\/salidas_guiadas\/gravel_odyssey_girona_rental_bicycle\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/tossacycling.com\/en\/shop\/salidas_guiadas\/gravel_odyssey_girona_rental_bicycle\/"]]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tossacycling.com\/en\/shop\/salidas_guiadas\/gravel_odyssey_girona_rental_bicycle\/#primaryimage","url":"https:\/\/tossacycling.com\/wp-content\/uploads\/2025\/07\/GOG.png","contentUrl":"https:\/\/tossacycling.com\/wp-content\/uploads\/2025\/07\/GOG.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/tossacycling.com\/en\/shop\/salidas_guiadas\/gravel_odyssey_girona_rental_bicycle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tossacycling.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/tossacycling.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Gravel Odyssey Girona + Rental Bike"}]},{"@type":"WebSite","@id":"https:\/\/tossacycling.com\/en\/#website","url":"https:\/\/tossacycling.com\/en\/","name":"TOSSA CYCLING","description":"CYCLING &amp; GOOD VIBES","publisher":{"@id":"https:\/\/tossacycling.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tossacycling.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/tossacycling.com\/en\/#organization","name":"TOSSA CYCLING","url":"https:\/\/tossacycling.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tossacycling.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/tossacycling.com\/wp-content\/uploads\/2022\/02\/cropped-squareRecurso-2.png","contentUrl":"https:\/\/tossacycling.com\/wp-content\/uploads\/2022\/02\/cropped-squareRecurso-2.png","width":512,"height":512,"caption":"TOSSA CYCLING"},"image":{"@id":"https:\/\/tossacycling.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TossaCycling","https:\/\/www.instagram.com\/tossacycling\/"]}]}},"_links":{"self":[{"href":"https:\/\/tossacycling.com\/en\/wp-json\/wp\/v2\/product\/44183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tossacycling.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tossacycling.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tossacycling.com\/en\/wp-json\/wp\/v2\/media\/44113"}],"wp:attachment":[{"href":"https:\/\/tossacycling.com\/en\/wp-json\/wp\/v2\/media?parent=44183"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tossacycling.com\/en\/wp-json\/wp\/v2\/product_brand?post=44183"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tossacycling.com\/en\/wp-json\/wp\/v2\/product_cat?post=44183"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tossacycling.com\/en\/wp-json\/wp\/v2\/product_tag?post=44183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}